{"id":1025847,"date":"2023-11-01T16:05:14","date_gmt":"2023-11-01T16:05:14","guid":{"rendered":"https:\/\/teknomers.com\/es\/en-la-opresiva-realidad-la-historia-de-un-denunciante-se-desarrolla-con-inquietante-eficacia-2\/"},"modified":"2023-11-01T16:05:18","modified_gmt":"2023-11-01T16:05:18","slug":"en-la-opresiva-realidad-la-historia-de-un-denunciante-se-desarrolla-con-inquietante-eficacia-2","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/en-la-opresiva-realidad-la-historia-de-un-denunciante-se-desarrolla-con-inquietante-eficacia-2\/","title":{"rendered":"En la opresiva Realidad, la historia de un denunciante se desarrolla con inquietante eficacia."},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"\">\n<figure class=\"artstyle__figure  artstyle__figure-landscape\" data-element-id=\"0dc29d25-96e4-4caa-b6ef-efa7b9f9d5fd\">\n<picture data-element-id=\"0dc29d25-96e4-4caa-b6ef-efa7b9f9d5fd\"><source  type=\"image\/webp\"><source  type=\"image\/jpeg\"><\/source><\/source><\/picture>\n<p><figcaption class=\"artstyle__figcaption\"><cite class=\"artstyle__figcaption__caption\">Sydney Sweeney en &#8216;Reality&#8217; de Tina Satter.<\/cite><\/figcaption><\/p>\n<\/figure>\n<p class=\"artstyle__paragraph \" data-element-id=\"059f-f626-b896-9e40-b195-7051-92d9-c104\">\n<p>      Las pel\u00edculas sobre denunciantes a menudo giran en torno a un dilema cl\u00e1sico: \u00bfel denunciante es un h\u00e9roe o un criminal?  Al infringir la ley, el denunciante a menudo cumple una funci\u00f3n crucial: compartir conocimientos con el mundo exterior que exponen una realidad dolorosa, a veces incluso criminal.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"15ca-e850-6a0f-0477-339a-152f-8c4a-b8f0\">\n<p>      La historia de Reality Winner encaja perfectamente en esa zona gris entre infringir la ley y la justicia.  Como empleado del servicio de seguridad estadounidense NSA, Winner filtr\u00f3 a la prensa en 2017 documentos secretos que demostraban que Rusia hab\u00eda interferido activamente en las elecciones presidenciales estadounidenses de 2016. Winner expuso as\u00ed graves grietas en los cimientos de la democracia, pero finalmente pag\u00f3 (solo). el precio de a\u00f1os de prisi\u00f3n.\n    <\/p>\n<div class=\"artstyle__container\" data-element-id=\"d5cb7588-0879-484e-91fc-cbb8862bfdba\">\n<div class=\"artstyle__container__body\">\n<p class=\"artstyle__container__text\" data-element-id=\"3938-f231-f3f7-c0c1-f415-9ef5-04f7-5257\">\n      <b>Sobre el Autor<\/b><b><br \/><\/b>Alex Mazereeuw escribe para <i>de Volkskrant<\/i> sobre televisi\u00f3n y cine y es cr\u00edtico de televisi\u00f3n una vez cada cinco semanas.\n    <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p class=\"artstyle__paragraph \" data-element-id=\"daae-37d3-dc9d-f625-f160-214f-25c6-05bc\">\n<p>      Winner explicar\u00eda m\u00e1s tarde que toda la situaci\u00f3n hab\u00eda sido traumatizante, especialmente el d\u00eda en que apareci\u00f3 el FBI con una orden de registro.  Las horas de interrogatorio que siguieron se grabaron en audio y la transcripci\u00f3n (p\u00fablica) volvi\u00f3 a constituir la base de la pel\u00edcula. <i>Realidad<\/i> de la directora debutante Tina Satter, quien anteriormente represent\u00f3 la historia en una obra de teatro.  Satter aporta esta forma teatral minimalista a su pel\u00edcula, que se basa casi palabra por palabra en la transcripci\u00f3n del FBI y tiene lugar en gran medida dentro y alrededor de la casa de Winner.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"63a4-f539-9835-cf00-168e-b211-29ea-0f82\">\n<p>      Este enfoque minimalista encaja perfectamente con la sensaci\u00f3n claustrof\u00f3bica que Winner (Sydney Sweeney, conocida por la serie de HBO <i>El loto blanco<\/i> y <i>Euforia<\/i>) experimenta desde el momento en que ve a los agentes del FBI (interpretados por Josh Hamilton y March\u00e1nt Davis) en su puerta.  Tienen una orden de registro porque Winner puede haber &#8220;manejado mal informaci\u00f3n clasificada&#8221;.  Seg\u00fan los agentes, la cooperaci\u00f3n es &#8220;voluntaria&#8221;, pero Winner tambi\u00e9n sabe que a partir de ese momento no tendr\u00e1 ad\u00f3nde ir.  Al principio, los oficiales todav\u00eda parecen amigables, pero en la angustiosa hora que sigue, Winner se ve arrinconado a\u00fan m\u00e1s por un criminal, sorprendentemente capturado en la amenazante diferencia de altura entre los oficiales y la peque\u00f1a Sweeney.\n    <\/p>\n<p class=\"artstyle__paragraph \" data-element-id=\"6559-f940-fbf9-6a4c-6627-89d2-4047-1ae0\">\n<p>      Lo que sigue es una confesi\u00f3n en c\u00e1mara lenta, en la que las (\u00bfbuenas?) intenciones de Winner son cada vez m\u00e1s aplastadas por la fr\u00eda letra de la ley. <i>Realidad<\/i> No es un thriller del gato y el rat\u00f3n, sino m\u00e1s bien un thriller en el que el rat\u00f3n sabe desde el principio que ha perdido.  Deje que la excelente Sweeney resalte ese hecho opresivo con sus ojos grandes y penetrantes y su expresi\u00f3n impotente.  Winner parece no tener ninguna posibilidad contra los guardianes del sistema, para quienes esta joven es considerada brevemente como el enemigo p\u00fablico n\u00famero uno durante el registro domiciliario.  No importa cu\u00e1n puras fueran sus intenciones, incluso en su peque\u00f1a casa la ley es una amenaza ineludible.\n    <\/p>\n<div class=\"artstyle__container\" data-element-id=\"46a4811c-71e6-4c2b-9bfb-befd0f2f7829\">\n<div class=\"artstyle__container__body\">\n<h4 class=\"artstyle__container__title\" data-element-id=\"d366-8404-bf35-4050-4bf9-33d4-72be-5f82\">\n      <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"container__title__icon\">\n        <path fill=\"#D00A10\" fill-rule=\"evenodd\" d=\"M0 0h6.5l4 4.5-4 4.5H0V0z\"\/>\n      <\/svg><\/p>\n<p>      Realidad<br \/>\n    <\/h4>\n<p class=\"artstyle__container__text\" data-element-id=\"b004-8d2c-177d-f701-0699-0fb4-dfbe-2b34\">\n<p>      Drama\n    <\/p>\n<p class=\"artstyle__container__text\" data-element-id=\"c83c-ca1d-ac71-eff6-31af-fcce-ca51-e64c\">\n<p>      \u2605\u2605\u2605\u2605\u2606\n    <\/p>\n<p class=\"artstyle__container__text\" data-element-id=\"0202-b479-62c7-8a5f-3276-9ca2-ac27-4bcb\">\n<p>      Dirigida por Tina Satter\n    <\/p>\n<p class=\"artstyle__container__text\" data-element-id=\"e570-8b83-4938-3bd0-b0a1-5fea-e94d-0d72\">\n<p>      Con Sydney Sweeney, Josh Hamilton y Marchant Davis\n    <\/p>\n<p class=\"artstyle__container__text\" data-element-id=\"0d7c-79a6-df6d-03b7-dbd8-c7c1-845c-994d\">\n<p>      85 minutos, en 36 salas.\n    <\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p><iframe id=\"sim_5829305088_1\" width=\"100%\" frameborder=\"0\" src=\"https:\/\/ims.volkskrant.nl\/optiext\/optiextension.dll?ID=MofMcIOTGz4_eO12zRZyy3_k1B2_oXSIXiWIOsaTs8K2w3C2xx7aMAL2GEFRfcLU_jR7lp0eNt4zq8CfIX&amp;guid=06A0B73C-0FE3-4E7E-8DB7-708E54B00603&amp;frameid=sim_5829305088_1\" loading=\"lazy\"><\/iframe><\/p>\n<aside class=\"artstyle__editorial-tips \" data-element-id=\"article-element-editorialtips\">\n<h3 class=\"editorial-tips__title\">Lea tambi\u00e9n<\/h3>\n<\/aside>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.volkskrant.nl\/cultuur-media\/in-het-benauwende-reality-wordt-het-verhaal-van-een-klokkenluider-allengs-zenuwslopender~bf4e97e3c\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-21<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sydney Sweeney en &#8216;Reality&#8217; de Tina Satter. Las pel\u00edculas sobre denunciantes a menudo giran en torno a un<\/p>\n","protected":false},"author":1,"featured_media":1025848,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[99,16282,4614,13544,1490,28507,89748,2862],"class_list":["post-1025847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-con","tag-denunciante","tag-desarrolla","tag-eficacia","tag-historia","tag-inquietante","tag-opresiva","tag-realidad"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1025847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1025847"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1025847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1025848"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1025847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1025847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1025847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}