{"id":1025641,"date":"2023-11-01T13:24:59","date_gmt":"2023-11-01T13:24:59","guid":{"rendered":"https:\/\/teknomers.com\/es\/el-precio-del-bitcoin-se-dispara-hasta-superar-los-30-000-euros\/"},"modified":"2023-11-01T13:25:03","modified_gmt":"2023-11-01T13:25:03","slug":"el-precio-del-bitcoin-se-dispara-hasta-superar-los-30-000-euros","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/el-precio-del-bitcoin-se-dispara-hasta-superar-los-30-000-euros\/","title":{"rendered":"El precio del Bitcoin se dispara hasta superar los 30.000 euros"},"content":{"rendered":"\n<div>\n\t\t\t\t\t\t\t\t<!-- Articles default Live football blog header --><\/p>\n<header class=\"article__header\">\n<p class=\"article__intro\">\n<p>\t\t\t\t\t\t\t\t\t\tBitcoin est\u00e1 subiendo de valor como loco.  En las \u00faltimas semanas, el precio se ha duplicado hasta superar los 30.000 euros y la subida de precio no parece terminar pronto.<\/p>\n<\/header>\n<p>\n\t<span class=\"article__source\"><br \/>\n\t\t<span itemprop=\"name\">Pete Vogels<\/span><br \/>\n\t<\/span><br \/>\n\t<time class=\"article__time\" datetime=\"01-11-23, 14:00\">11-01-23, 14:00<\/time><\/p>\n<p>\t<span class=\"article__update\"><\/p>\n<p>\t<\/span><br \/>\n\t<span class=\"article__credit\"><\/p>\n<p>\t<\/span>\n<\/p>\n<p><meta itemprop=\"datePublished\" content=\"2023-11-01T14:00:29.278+01:00\"\/><br \/>\n<span><br \/>\n\t<span><br \/>\n\t\t<meta content=\"https:\/\/statics.ad.nl\/img\/brand-logo-1c231bf304.png\"\/><br \/>\n\t\t<meta content=\"90\"\/><br \/>\n\t\t<meta content=\"90\"\/><br \/>\n\t<\/span><br \/>\n\t<meta content=\"AD\"\/><br \/>\n<\/span><\/p>\n<p>\t\t\t\t\t\t\t\t<!-- includes\/general\/sharing.html --><\/p>\n<p><!-- \/ includes\/general\/sharing.html --><\/p>\n<div class=\"article__body fjs-login-gate fjs-load-remaining-content\" data-remaining-content-url=\"\/article\/remaining-content\/~a6036e599\">\n<div class=\"article-login-gate fjs-article-login-gate\">\n<p class=\"article-login-gate__title fjs-article-login-gate__title\">\n<p>\t\t\u00bfAcceso ilimitado y gratuito a Showbytes?  \u00a1Qu\u00e9 puede!\n\t<\/p>\n<p>\t<span class=\"article-login-gate__info fjs-article-login-gate__info\"><\/p>\n<p>\t\tInicia sesi\u00f3n o crea una cuenta y no te pierdas nada de las estrellas.<br \/>\n\t<\/span><\/p>\n<p class=\"article-login-gate__buttonholder\">\n<p>\t\t\t<span class=\"button__text fjs-article-login-gate__button\">S\u00ed, quiero acceso ilimitado y gratuito.<\/span><\/p>\n<\/div>\n<p>\t\t\t\t\t\t\t\t\t<!-- includes\/advertising\/fixed-slot.html --><\/p>\n<p><!-- \/ includes\/advertising\/fixed-slot.html --><\/p><\/div>\n<footer class=\"article__footer\">\n<\/footer><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.ad.nl\/economie\/koers-bitcoin-schiet-omhoog-tot-boven-de-30-000-euro~a6036e599\/\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-43<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bitcoin est\u00e1 subiendo de valor como loco. En las \u00faltimas semanas, el precio se ha duplicado hasta superar<\/p>\n","protected":false},"author":1,"featured_media":1025642,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2131,38,5709,1477,63,36,2539,20534],"class_list":["post-1025641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-bitcoin","tag-del","tag-dispara","tag-euros","tag-hasta","tag-los","tag-precio","tag-superar"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1025641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1025641"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1025641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1025642"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1025641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1025641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1025641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}