{"id":1025638,"date":"2023-11-01T13:22:24","date_gmt":"2023-11-01T13:22:24","guid":{"rendered":"https:\/\/teknomers.com\/es\/en-el-espectaculo-de-danza-breathe-la-persona-sobreestimulada-busca-tranquilidad-a-traves-de-la-respiracion\/"},"modified":"2023-11-01T13:22:27","modified_gmt":"2023-11-01T13:22:27","slug":"en-el-espectaculo-de-danza-breathe-la-persona-sobreestimulada-busca-tranquilidad-a-traves-de-la-respiracion","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/en-el-espectaculo-de-danza-breathe-la-persona-sobreestimulada-busca-tranquilidad-a-traves-de-la-respiracion\/","title":{"rendered":"En el espect\u00e1culo de danza &#8216;Breathe&#8217;, la persona sobreestimulada busca tranquilidad a trav\u00e9s de la respiraci\u00f3n"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Encontrar libertad, paz y tranquilidad dentro de uno mismo es m\u00e1s importante en la filosof\u00eda india que superar las limitaciones externas.  Todo yogui aficionado sabe lo que es importante: la respiraci\u00f3n.  eso comienza <em>Respirar<\/em> del core\u00f3grafo Kalpana Raghuraman: los cinco bailarines y cuatro m\u00fasicos del Matangi Quartet entran tranquilamente a la pista.  En la relajante luz azul que marca los l\u00edmites de la superficie de juego en l\u00edneas estrechas, inhalan y exhalan en una cadencia colectiva, mientras balancean suavemente sus cuerpos hacia adelante y hacia atr\u00e1s, como ca\u00f1as que se balancean.<\/p>\n<aside class=\"dmt-article-side dmt-article-side--review vorm__article-content-positioned vorm__article-content-positioned--left\">\n<div class=\"dmt-article-side__content\">\n<div class=\"dmt-article-side__text\">\n<div>\n<p><span class=\"keyword\">Bailar<\/span><\/p>\n<p>Respira de Kalpana Raghuraman y Matangi Quartet.  Visto: 31\/10, Teatro Bellevue Amsterdam.  Informaci\u00f3n: <a rel=\"nofollow noopener\" href=\"https:\/\/kalpanarts.com\/repertoire\/Breathe-1\" target=\"_blank\">www.kalpanarts.com<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/aside>\n<p>Una vez que los m\u00fasicos han tomado asiento, comienza un poderoso baile conjunto, con movimientos de brazos muy articulados, angulados o dibujando l\u00edneas limpias.  En d\u00faos cortos, los bailarines se empujan hacia adelante o se desequilibran, mientras los dem\u00e1s miran al fondo.  De nuevo juntos, vuelven a sincronizar sus cuerpos, con una especie de &#8216;pops&#8217; en el torso que poco a poco se convierten en saltos erguidos y, finalmente, en un baile r\u00edtmico.<\/p>\n<h2 class=\"gn4-crosshead article-heading\">danza india<\/h2>\n<p>Las ra\u00edces de Raghuraman en la danza india son claramente reconocibles en los feroces ritmos de los pies y los movimientos de los brazos colocados con precisi\u00f3n.  El bailar\u00edn Sooraj Subramaniam comparte esos antecedentes.  Su hermosa precisi\u00f3n le da a su solo, acompa\u00f1ado por el violonchelista Arno van der Vuurst, y a su interpretaci\u00f3n un lugar destacado dentro del grupo.  Pero tambi\u00e9n hay claras diferencias en la forma en que buscan su tranquilidad interior en los solos de los otros cuatro.  A veces los contornos son m\u00e1s suaves y rizados (Laila Gozzi), fluidos continuamente (Riccardo Zandon\u00e1), agresivos (Frederik Kaijser) o agresivos y poderosos (Manouk Schrauwen). <\/p>\n<p><dmt-slider aspectratio=\"3:2\" class=\"vorm__article-content-positioned vorm__article-content-positioned--width-website\" objectfit=\"none\" width=\"site\"><\/p>\n<figure class=\"carousel-cell\" data-aspect-ratio=\"0.66673047473201\"><picture><\/picture><dmt-image-caption><span class=\"tekst\"><span class=\"caption-text\">Espect\u00e1culo de danza &#8216;<strong>Respirar<\/strong>&#8216; por Kalpanarts.<\/span><\/span><span class=\"producer\"><span class=\"caption-producer\">Foto Bowie Verschuren<\/span><\/span><\/dmt-image-caption><\/figure>\n<figure class=\"carousel-cell\" data-aspect-ratio=\"0.66727638558624\"><picture><img decoding=\"async\" alt=\"\" class=\"b-lazy\" data-aspect-ratio=\"0.66727638558624\" data-flickity-lazyload=\"\/\/images.nrc.nl\/GKfga8BGO8c6EH0aTRi9_MiBE08=\/640x\/smart\/filters:no_upscale():strip_icc()\/s3\/static.nrc.nl\/bvhw\/files\/2023\/11\/data107479706-c14e37.jpg\" data-open-in-lightbox=\"true\" src=\"https:\/\/images.nrc.nl\/xNmGXrfGLpG6x9L5-4tsUVrPfTI=\/1360x\/smart\/filters:no_upscale():strip_icc()\/s3\/static.nrc.nl\/bvhw\/files\/2023\/11\/data107479706-c14e37.jpg|\/\/images.nrc.nl\/FbIgUFJ7QML-A-lQn91ysmFGRNk=\/1920x\/smart\/filters:no_upscale():strip_icc()\/s3\/static.nrc.nl\/bvhw\/files\/2023\/11\/data107479706-c14e37.jpg|\/\/images.nrc.nl\/ZQXudzFdnvrXkRbPqn79oNCkynM=\/5760x\/smart\/filters:no_upscale():strip_icc()\/s3\/static.nrc.nl\/bvhw\/files\/2023\/11\/data107479706-c14e37.jpg\" src-medium=\"\/\/images.nrc.nl\/GKfga8BGO8c6EH0aTRi9_MiBE08=\/640x\/smart\/filters:no_upscale():strip_icc()\/s3\/static.nrc.nl\/bvhw\/files\/2023\/11\/data107479706-c14e37.jpg|\/\/images.nrc.nl\/xNmGXrfGLpG6x9L5-4tsUVrPfTI=\/1360x\/smart\/filters:no_upscale():strip_icc()\/s3\/static.nrc.nl\/bvhw\/files\/2023\/11\/data107479706-c14e37.jpg\" bad-src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABCAAAAAA6fptVAAAACklEQVQI12N4AwAA7gDtOcCbowAAAABJRU5ErkJggg==\"\/><\/picture><dmt-image-caption><span class=\"tekst\"><span class=\"caption-text\">Espect\u00e1culo de danza &#8216;<strong>Respirar<\/strong>&#8216; por Kalpanarts.<\/span><\/span><span class=\"producer\"><span class=\"caption-producer\">Foto Bowie Verschuren<\/span><\/span><\/dmt-image-caption><\/figure>\n<p><\/dmt-slider><\/p>\n<p>Los bailes del grupo adquieren un car\u00e1cter marcial a trav\u00e9s de gritos breves y respiraciones pesadas, en las que los bailarines parecen sufrir una sobreestimulaci\u00f3n.  Los movimientos son fren\u00e9ticos, entrecortados y concisos.  La m\u00fasica tambi\u00e9n avanza hasta un crescendo, despu\u00e9s del cual los m\u00fasicos, como en el <em>Sinfon\u00eda de despedida<\/em>, uno a uno detienen su juego para unirse a los bailarines.  Finalmente, vuelven a estar juntos en el suelo, respirando juntos en pac\u00edfica tranquilidad.<\/p>\n<p>Las diferentes partes est\u00e1n claramente marcadas, con un cambio de luz (del azul al rosa o al blanco) y una nueva parte de la m\u00fasica del compositor Simone Giacomini.  Esto se combina alternativamente con percusi\u00f3n pregrabada.  Aunque algunas danzas en conjunto son hermosas por su simplicidad (saltar juntos en posici\u00f3n vertical) y los solos son fascinantes, debido a la cesura recurrente, en realidad no suman nada m\u00e1s que una colecci\u00f3n de danzas en torno al tema. <em>Respirar<\/em> sin embargo, tiene mucha belleza que ofrecer, sobre todo gracias a la atm\u00f3sfera reflexiva que Giacomini cre\u00f3 especialmente para esta actuaci\u00f3n, inspirada en la obra minimalista de Simeon ten Holt: repetitiva, minimalista, melanc\u00f3lica y respirable.<\/p>\n<p><span class=\"gn4-embed\"><dmt-youtube><a rel=\"nofollow noopener\" href=\"https:\/\/www.youtube.com\/watch?v=D7Dh4hdgqm4\" target=\"_blank\">https:\/\/www.youtube.com\/watch?v=D7Dh4hdgqm4<\/a><\/dmt-youtube><\/span><\/p>\n<aside data-article-id=\"4179328\" data-js-topic-preview=\"\" data-strip-from-headless=\"modal\" data-topic-id=\"172\" data-topic-name=\"Theater\"\/>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nrc.nl\/nieuws\/2023\/11\/01\/in-dansvoorstelling-breathe-zoekt-de-overprikkelde-mens-via-de-adem-verstilling-a4179328\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-33<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Encontrar libertad, paz y tranquilidad dentro de uno mismo es m\u00e1s importante en la filosof\u00eda india que superar<\/p>\n","protected":false},"author":1,"featured_media":1025639,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[68428,6410,2963,1658,5389,16467,213172,48464,116],"class_list":["post-1025638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-breathe","tag-busca","tag-danza","tag-espectaculo","tag-persona","tag-respiracion","tag-sobreestimulada","tag-tranquilidad","tag-traves"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1025638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1025638"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1025638\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1025639"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1025638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1025638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1025638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}