{"id":1019793,"date":"2023-10-28T15:46:00","date_gmt":"2023-10-28T15:46:00","guid":{"rendered":"https:\/\/teknomers.com\/es\/nueva-fase-de-la-ofensiva-israeli-en-gaza-principalmente-provista-de-un-sistema-de-tuneles\/"},"modified":"2023-10-28T15:46:04","modified_gmt":"2023-10-28T15:46:04","slug":"nueva-fase-de-la-ofensiva-israeli-en-gaza-principalmente-provista-de-un-sistema-de-tuneles","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/nueva-fase-de-la-ofensiva-israeli-en-gaza-principalmente-provista-de-un-sistema-de-tuneles\/","title":{"rendered":"&#8216;Nueva fase&#8217; de la ofensiva israel\u00ed en Gaza, principalmente &#8216;provista de un sistema de t\u00faneles&#8217;"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Fuertes bombardeos, cortes de telecomunicaciones, entrada de tropas terrestres: los informes procedentes de la Franja de Gaza indicaron una importante escalada de la guerra entre Israel y Ham\u00e1s.  Volker T\u00fcrk, Alto Comisionado de las Naciones Unidas para los Derechos Humanos, advirti\u00f3 el s\u00e1bado sobre las &#8220;consecuencias potencialmente catastr\u00f3ficas&#8221; de la operaci\u00f3n israel\u00ed en Gaza. <\/p>\n<p>  \u201cLa violencia continua no es la soluci\u00f3n\u201d, afirm\u00f3 T\u00fcrk, que teme que \u201cmiles de civiles\u201d puedan morir a causa de los ataques intensificados.  Pidi\u00f3 a las partes en conflicto y a los Estados con influencia en la regi\u00f3n &#8220;que hagan todo lo que est\u00e9 a su alcance para reducir la intensidad de este conflicto&#8221;. <\/p>\n<p>Los analistas se preguntaban qu\u00e9 estaba sucediendo exactamente.  \u00bfEs esta la invasi\u00f3n terrestre que Israel viene anunciando desde hace tiempo?<\/p>\n<p>Se trata en parte de una cuesti\u00f3n sem\u00e1ntica: despu\u00e9s de todo, en las \u00faltimas semanas se ha hablado de una presencia militar israel\u00ed en Gaza.  El general de brigada Han Bouwmeester, profesor de ciencias operacionales militares en la Academia de Defensa holandesa, tiene en cuenta que poco despu\u00e9s del ataque a gran escala de Ham\u00e1s el 7 de octubre, las tropas de \u00e9lite israel\u00edes (<em>fuerzas especiales<\/em>) entr\u00f3 en Gaza. <\/p>\n<p>\u201cNo lo sabemos con seguridad, porque este tipo de operaciones son secretas por definici\u00f3n.  Pero es probable que enviaran soldados por delante para recopilar informaci\u00f3n.  \u00bfD\u00f3nde est\u00e1 Ham\u00e1s, cu\u00e1l es su cuartel general, d\u00f3nde est\u00e1n los lugares de lanzamiento de cohetes, d\u00f3nde est\u00e1n los rehenes? <\/p>\n<p>\u00c9sta, dice Bouwmeester, fue la &#8220;etapa preliminar&#8221; para una ofensiva terrestre.  \u201cNo s\u00f3lo mides d\u00f3nde est\u00e1n, sino tambi\u00e9n c\u00f3mo reaccionan ante tu presencia.  Esto proporciona informaci\u00f3n valiosa sobre c\u00f3mo organizar tus propias tropas\u201d.<\/p>\n<h2 class=\"gn4-crosshead article-heading\">Lluvia de bombas sobre la red de t\u00faneles de Ham\u00e1s<\/h2>\n<p>Seg\u00fan Bouwmeester, el viernes por la noche comenz\u00f3 una &#8220;nueva fase&#8221;.  Seg\u00fan la agencia de noticias Reuters, el ej\u00e9rcito israel\u00ed ha entrado en la franja de tierra por dos lugares, con topadoras blindadas, tanques y veh\u00edculos pesados \u200b\u200bde combate de infanter\u00eda a la vanguardia.  Un lugar es Beit Hanoun, la ciudad m\u00e1s al noreste de Gaza;  La otra invasi\u00f3n terrestre habr\u00eda tenido lugar en el campo de refugiados de Bureij, en el centro de la franja de tierra.<\/p>\n<p>Esta entrada estuvo acompa\u00f1ada de una lluvia de bombas a gran escala sobre la Franja de Gaza, llevada a cabo por un centenar de aviones de combate.  Estas bombas ten\u00edan como objetivo principal destruir la extensa red de t\u00faneles de Ham\u00e1s.  Seg\u00fan varios medios, Israel ha atacado m\u00e1s de ciento cincuenta t\u00faneles y b\u00fankeres.  Israel tambi\u00e9n utiliz\u00f3 fuego de artiller\u00eda contra las primeras l\u00edneas de defensa de Ham\u00e1s.<\/p>\n<p>Seg\u00fan Bouwmeester, estas acciones de combate despejan el camino para las tropas terrestres.  Esto no significa que los 360.000 reservistas entrar\u00e1n a la vez en esa franja de tierra, afirma.  \u201cLa BBC inform\u00f3 que Israel <em>rebanada por rebanada<\/em> entra en Gaza, y eso me parece realmente plausible.  Si van todos a la vez, se interponen en el camino de los dem\u00e1s.  Adem\u00e1s, en Gaza s\u00f3lo hay un n\u00famero limitado de carreteras\u201d.<\/p>\n<p>Adem\u00e1s, dice el profesor, Israel tambi\u00e9n necesita mano de obra en la frontera.  \u201cDe manera un poco irrespetuosa, se puede comparar con un tubo de pasta de dientes que se vac\u00eda: los combatientes de Ham\u00e1s que son expulsados \u200b\u200btienen que ir a alguna parte.  La franja no es grande, por lo que tal vez terminen en la frontera con Israel\u201d.<\/p>\n<p><dmt-image-wrapper class=\"vorm__article-content-positioned vorm__article-content-positioned--right\"><\/p>\n<figure class=\"inline\" data-source=\"gn4\">\n<picture><\/picture>\n<\/figure>\n<p><\/dmt-image-wrapper><\/p>\n<h2 class=\"gn4-crosshead article-heading\">Invasi\u00f3n terrestre masiva<\/h2>\n<p>Bouwmeester no espera en absoluto un ataque a gran escala en forma de una invasi\u00f3n terrestre masiva en esta guerra.  \u201cEstados Unidos est\u00e1 ejerciendo demasiada presi\u00f3n para no hacer eso.  Y aunque Israel a veces se muestra descarriado, necesita el apoyo estadounidense\u201d.<\/p>\n<p>Israel querr\u00e1 limpiar bloque residencial tras bloque residencial, barrio tras barrio, de militantes de Hamas, dice Bouwmeester.  &#8220;Los t\u00faneles plantean naturalmente un problema a este respecto, porque los combatientes pueden desaparecer en ellos y salir de ellos&#8221;.<\/p>\n<p><dmt-icon class=\"dmt-article-suggestion__icon\" name=\"ic-forward\"\/><\/p>\n<p>\n<strong class=\"dmt-article-suggestion__text-label\">Lea tambi\u00e9n<\/strong><br \/>\n<span>el blog en vivo<\/span>\n<\/p>\n<p><img decoding=\"async\" alt=\"Testigos de Gaza: 'Fuertes bombardeos alrededor de dos hospitales en la ciudad de Gaza'\" class=\"dmt-article-suggestion__image\" src=\"https:\/\/teknomers.com\/es\/wp-content\/uploads\/2023\/10\/Nueva-fase-de-la-ofensiva-israeli-en-Gaza-principalmente-provista.jpg\"\/><\/p>\n<p>Seg\u00fan el general de brigada, el hecho de que Israel se centre ahora principalmente en los t\u00faneles se desprende de la visita que el Primer Ministro Benjam\u00edn Netanyahu realiz\u00f3 al yahalom, el genio del ej\u00e9rcito.  Ese es el departamento que desactiva explosivos y minas, y construye puentes y casas.  Parte de esta es la unidad samur, que se dedica a encontrar y destruir t\u00faneles.  &#8220;La visita de Netanyahu deja claro cu\u00e1les son las prioridades&#8221;.<\/p>\n<p>El mayor problema para Israel es la ubicaci\u00f3n de los rehenes.  El testimonio del reh\u00e9n liberado previamente, Yocheved Lifshitz, demostr\u00f3 que sus secuestradores la reten\u00edan en la red de t\u00faneles.  En este momento no se puede decir con certeza c\u00f3mo Israel est\u00e1 tratando de librarlos de los ataques.<\/p>\n<h2 class=\"gn4-crosshead article-heading\">Ciudadanos abandonados<\/h2>\n<p>El estratega de guerra Mick Ryan elabora <a rel=\"nofollow noopener\" href=\"https:\/\/mickryan.substack.com\/p\/assault-into-gaza\" target=\"_blank\">su blog<\/a> que Israel habr\u00e1 utilizado los recientes ataques contra Gaza principalmente &#8220;para recopilar informaci\u00f3n de inteligencia sobre el impacto de los ataques a\u00e9reos israel\u00edes, sobre el n\u00famero de civiles que quedan en zonas donde Israel podr\u00eda llevar a cabo ataques a mayor escala y sobre las respuestas de Ham\u00e1s&#8221;.<\/p>\n<p>Los israel\u00edes, dice Ryan, se est\u00e1n moviendo r\u00e1pidamente y lanzando ataques en muchos lugares diferentes.  &#8220;Esto no s\u00f3lo tendr\u00e1 como objetivo confundir a los comandantes de Ham\u00e1s sobre lo que est\u00e1 sucediendo y por qu\u00e9, sino que tambi\u00e9n garantizar\u00e1 que las respuestas de los l\u00edderes de Ham\u00e1s siempre lleguen un poco tarde para importar&#8221;.  Estas acciones r\u00e1pidas tambi\u00e9n tienen como objetivo alentar a los combatientes de Ham\u00e1s a salir y luchar para poder localizarlos y eliminarlos.<\/p>\n<p><dmt-image-wrapper><\/p>\n<figure class=\"gn4-inline\" data-source=\"gn4\">\n<picture><img decoding=\"async\" class=\"b-lazy\" data-aspect-ratio=\"0.6671650158848813\" data-gn4-data-id=\"data107300915\" data-open-in-lightbox=\"\" src=\"https:\/\/images.nrc.nl\/fXEI4UlxYpFX5neyrmSKCGIo5NI=\/1280x\/filters:no_upscale()\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107300915-ebe320.jpg|https:\/\/images.nrc.nl\/IChgGSO2GJ2MKUan0_GTBADnIys=\/1920x\/filters:no_upscale()\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107300915-ebe320.jpg|https:\/\/images.nrc.nl\/kFYTXTH-8Z2nJJbg2ZPcbYtjr4Q=\/5760x\/filters:no_upscale()\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107300915-ebe320.jpg\" src-medium=\"https:\/\/images.nrc.nl\/HJise9Tdzi8D7TdcLgcOdbOIc5U=\/640x\/filters:no_upscale()\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107300915-ebe320.jpg|https:\/\/images.nrc.nl\/fXEI4UlxYpFX5neyrmSKCGIo5NI=\/1280x\/filters:no_upscale()\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107300915-ebe320.jpg\" src-medium-webp=\"https:\/\/images.nrc.nl\/cu7r9AnN6M1CIWXng2fpcBEv12A=\/640x\/filters:no_upscale():format(webp)\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107300915-ebe320.jpg|https:\/\/images.nrc.nl\/P-QxgElXnU1TeG4eRM5pDnS_pQg=\/1280x\/filters:no_upscale():format(webp)\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107300915-ebe320.jpg\" src-webp=\"https:\/\/images.nrc.nl\/P-QxgElXnU1TeG4eRM5pDnS_pQg=\/1280x\/filters:no_upscale():format(webp)\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107300915-ebe320.jpg|https:\/\/images.nrc.nl\/ZWsPYrOAPoptNUUeHWdpAtei394=\/1920x\/filters:no_upscale():format(webp)\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107300915-ebe320.jpg|https:\/\/images.nrc.nl\/lnSJKdvSD_ek3mBmGSS8IftZAjs=\/5760x\/filters:no_upscale():format(webp)\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107300915-ebe320.jpg\" bad-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\"\/><dmt-image-caption>Cola para conseguir agua potable en la ciudad de Gaza.  La ciudad fue atacada por el ej\u00e9rcito israel\u00ed la noche del viernes al s\u00e1bado.<\/dmt-image-caption><\/picture><figcaption>\n<span class=\"caption-producer\">Foto Mohammed Abed\/AFP<\/span><br \/>\n<\/figcaption><\/figure>\n<p><\/dmt-image-wrapper><\/p>\n<p>Seg\u00fan Ryan, las incursiones a peque\u00f1a escala tambi\u00e9n se habr\u00e1n utilizado para convencer a los civiles restantes de que Israel tomaba en serio la orden de evacuaci\u00f3n.  En tercer lugar, este ataque servir\u00eda como una especie de punta de lanza en el agua de la piscina: evaluar c\u00f3mo responden Estados Unidos y sus aliados europeos a las fuerzas terrestres israel\u00edes en Gaza.<\/p>\n<p>S\u00e1bado por la tarde <a rel=\"nofollow noopener\" href=\"https:\/\/twitter.com\/IDF\/status\/1718240244129059167\" target=\"_blank\">el ej\u00e9rcito israel\u00ed publicado en X<\/a>, anteriormente Twitter, un nuevo llamado a los residentes de la Franja de Gaza para que evacuen el norte de Gaza.  \u201cAtenci\u00f3n, residentes de Gaza.  Escucha cuidadosamente.  Este es un consejo militar urgente del ej\u00e9rcito israel\u00ed.  Para su seguridad inmediata, pedimos a todos los residentes del norte de Gaza y de la ciudad de Gaza que se reasienten temporalmente en el sur. [\u2026] Esta es una medida temporal.  Regresar al norte de Gaza ser\u00e1 posible cuando terminen las intensas hostilidades\u201d. <\/p>\n<p>Con este llamado, Israel aborda el temor entre algunos palestinos de que se avecina una nueva Nakba (cat\u00e1strofe).  Este acontecimiento se refiere al periodo 1947-1949, cuando unos 750.000 palestinos se vieron obligados a abandonar sus hogares en lo que hoy es Israel.  Muchos de ellos terminaron en uno de los campos de refugiados de Gaza. <\/p>\n<h2 class=\"gn4-crosshead article-heading\">Sin internet ni tel\u00e9fono<\/h2>\n<p>Debido al corte de las telecomunicaciones, este v\u00eddeo no ser\u00e1 visible para la mayor\u00eda de los residentes de Gaza.  Los periodistas palestinos y las organizaciones de ayuda en Gaza apenas tienen contacto con el mundo exterior.  A trav\u00e9s de <a rel=\"nofollow noopener\" href=\"https:\/\/twitter.com\/Hind_Gaza\/status\/1718153129961689097\" target=\"_blank\">su cuenta x<\/a> El periodista Hind Khoudary a\u00fan pudo difundir mensajes.  Seg\u00fan ella, los bombardeos israel\u00edes han causado numerosas v\u00edctimas mortales, especialmente en el campo de refugiados de Al-Shati, cerca de la ciudad de Gaza, tambi\u00e9n conocido como Beach Camp.<\/p>\n<p>Seg\u00fan varios testimonios recogidos por la agencia de noticias AFP, los bombardeos m\u00e1s intensos se concentraron en las zonas cercanas a dos hospitales de la ciudad de Gaza.  Se trata del llamado hospital indonesio, construido con donaciones de Indonesia, y del hospital Al-Shifa, el hospital m\u00e1s grande de Gaza. <\/p>\n<p><dmt-image-wrapper><\/p>\n<figure class=\"gn4-inline\" data-source=\"gn4\">\n<picture><img decoding=\"async\" class=\"b-lazy\" data-aspect-ratio=\"0.6673893405600723\" data-gn4-data-id=\"data107301490\" data-open-in-lightbox=\"\" src=\"https:\/\/images.nrc.nl\/HcEr1kdAdj06oMTGB8S_OdmUOVk=\/1280x\/filters:no_upscale()\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107301490-42b9a0.jpg|https:\/\/images.nrc.nl\/WQJKqfWRPwRv1-H5gQL1ZFLd5cA=\/1920x\/filters:no_upscale()\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107301490-42b9a0.jpg|https:\/\/images.nrc.nl\/g6ha9NRgGEULn93ujv39XAWXzPw=\/5760x\/filters:no_upscale()\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107301490-42b9a0.jpg\" src-medium=\"https:\/\/images.nrc.nl\/ZO_VAo_q6_wc25y_2Uv7UmsZHFk=\/640x\/filters:no_upscale()\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107301490-42b9a0.jpg|https:\/\/images.nrc.nl\/HcEr1kdAdj06oMTGB8S_OdmUOVk=\/1280x\/filters:no_upscale()\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107301490-42b9a0.jpg\" src-medium-webp=\"https:\/\/images.nrc.nl\/UUQ6ZdtoHN3rdo9yRFgYjwNbEUw=\/640x\/filters:no_upscale():format(webp)\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107301490-42b9a0.jpg|https:\/\/images.nrc.nl\/Ude7j7prCA3FPlWQ_NAEpwX5vjs=\/1280x\/filters:no_upscale():format(webp)\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107301490-42b9a0.jpg\" src-webp=\"https:\/\/images.nrc.nl\/Ude7j7prCA3FPlWQ_NAEpwX5vjs=\/1280x\/filters:no_upscale():format(webp)\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107301490-42b9a0.jpg|https:\/\/images.nrc.nl\/X8jwyQxFkipn-snnAPhFyh33fJ0=\/1920x\/filters:no_upscale():format(webp)\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107301490-42b9a0.jpg|https:\/\/images.nrc.nl\/z1iMDg8tJLhrVgqs6W_8vDY8YD4=\/5760x\/filters:no_upscale():format(webp)\/s3\/static.nrc.nl\/images\/gn4\/stripped\/data107301490-42b9a0.jpg\" bad-src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\"\/><dmt-image-caption>Tambi\u00e9n se bombardearon edificios en el sur de la Franja de Gaza, como aqu\u00ed en Rafah.<\/dmt-image-caption><\/picture><figcaption>\n<span class=\"caption-producer\">Foto Said Khatib\/AFP<\/span><br \/>\n<\/figcaption><\/figure>\n<p><\/dmt-image-wrapper><\/p>\n<p>La interrupci\u00f3n de Internet, sostiene Ryan, ayudar\u00e1 a Israel a derribar las redes de mando de Ham\u00e1s.  Esto hace que no quede claro, especialmente para los ciudadanos, las organizaciones de ayuda y los medios de comunicaci\u00f3n, qu\u00e9 est\u00e1 sucediendo exactamente.<\/p>\n<p>Phillipe Lazzarini, jefe de la organizaci\u00f3n de la ONU UNRWA, est\u00e1 &#8220;muy preocupado&#8221; por sus empleados en Gaza.  En una carta dirigida al personal el s\u00e1bado, escribi\u00f3 que a\u00fan no hab\u00eda podido establecer contacto con &#8220;la gran mayor\u00eda&#8221; de su equipo en la Franja de Gaza desde que los ataques israel\u00edes se intensificaron el viernes por la noche y se cortaron las l\u00edneas de comunicaci\u00f3n.  &#8220;Esto me preocupa mucho por mis colegas y sus familias&#8221;.  La UNRWA se ocupa de los refugiados palestinos en la regi\u00f3n.<\/p>\n<p>Los propios combatientes de Ham\u00e1s se ven menos afectados por la interrupci\u00f3n de Internet, opina el profesor Bouwmeester.  &#8220;Sin duda se han asegurado de poder seguir comunic\u00e1ndose en tal situaci\u00f3n&#8221;.<\/p>\n<p>Con la cooperaci\u00f3n de <span class=\"byline\">Mandula van den Berg<\/span> y <span class=\"byline\">Flori Hofman<\/span>\n<\/p>\n<aside data-article-id=\"4178915\" data-js-topic-preview=\"\" data-strip-from-headless=\"modal\" data-topic-id=\"122\" data-topic-name=\"Midden-Oosten\"\/>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/www.nrc.nl\/nieuws\/2023\/10\/28\/nieuwe-fase-in-israelisch-offensief-in-gaza-vooral-voorzien-op-tunnelstelsel-a4178915\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-33<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fuertes bombardeos, cortes de telecomunicaciones, entrada de tropas terrestres: los informes procedentes de la Franja de Gaza indicaron<\/p>\n","protected":false},"author":1,"featured_media":1019794,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[1534,51742,12592,212,499,6411,105463,5321,48801],"class_list":["post-1019793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-fase","tag-gaza","tag-israeli","tag-nueva","tag-ofensiva","tag-principalmente","tag-provista","tag-sistema","tag-tuneles"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1019793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1019793"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1019793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1019794"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1019793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1019793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1019793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}