{"id":1019696,"date":"2023-10-28T14:14:00","date_gmt":"2023-10-28T14:14:00","guid":{"rendered":"https:\/\/teknomers.com\/es\/atrasar-el-reloj-una-hora-cuales-son-los-beneficios-del-horario-de-invierno\/"},"modified":"2023-10-28T14:14:04","modified_gmt":"2023-10-28T14:14:04","slug":"atrasar-el-reloj-una-hora-cuales-son-los-beneficios-del-horario-de-invierno","status":"publish","type":"post","link":"https:\/\/teknomers.com\/es\/atrasar-el-reloj-una-hora-cuales-son-los-beneficios-del-horario-de-invierno\/","title":{"rendered":"Atrasar el reloj una hora: \u00bfcu\u00e1les son los beneficios del horario de invierno?"},"content":{"rendered":"\n<div>\n<p>Los relojes se retrasar\u00e1n una hora esta noche.  Eso significa una hora extra de sue\u00f1o, pero para muchas personas tambi\u00e9n significa una alteraci\u00f3n en su ritmo de sue\u00f1o.  A menudo hablamos de esos aspectos negativos, pero \u00bfpor qu\u00e9 distinguimos entre verano e invierno y cu\u00e1les son exactamente sus ventajas? <\/p>\n<\/div>\n<div>\n<p>El horario de invierno es el horario &#8220;original&#8221;.  A lo largo del siglo XX, el horario de verano se introdujo varias veces en toda Europa, pero se introdujo definitivamente en 1977.  Esto se debi\u00f3 a que en ese momento hab\u00eda una crisis petrolera tan grande que la gente quer\u00eda hacer todo lo posible para ahorrar la mayor cantidad de energ\u00eda posible. <\/p>\n<p>El horario de verano permite aprovechar la luz natural del exterior durante una hora m\u00e1s.  Si dej\u00e1ramos el reloj en la hora original (invierno), en verano ya amanecer\u00eda a las 4:30 de la ma\u00f1ana.  La mayor\u00eda de las personas a\u00fan no est\u00e1n despiertas, por lo que tiene sentido cambiar el reloj una hora.  De esta manera habr\u00e1 luz durante una hora m\u00e1s por la noche, cuando mucha gente est\u00e1 despierta. <\/p>\n<h2>Beneficios del horario de invierno<\/h2>\n<p>Seg\u00fan la RIVM, el horario de invierno tambi\u00e9n tiene otras ventajas.  La investigaci\u00f3n de la literatura internacional ha demostrado que un amanecer temprano se adapta mucho mejor a los biorritmos humanos.  Por ello, el RIVM aboga por la introducci\u00f3n del horario de invierno como est\u00e1ndar. <\/p>\n<p>Seg\u00fan el instituto nacional, muchas personas sufren el cambio de hora.  Especialmente despu\u00e9s del inicio del horario de verano, la gente duerme mal porque tiene una hora menos.  Seg\u00fan el instituto, inmediatamente despu\u00e9s del cambio al horario de verano se producen m\u00e1s ataques card\u00edacos. <\/p>\n<p>Seg\u00fan el RIVM, fijar el horario de verano como horario est\u00e1ndar tendr\u00eda efectos negativos para la salud p\u00fablica. <\/p>\n<h2>La Comisi\u00f3n Europea toma una decisi\u00f3n <\/h2>\n<p>La Comisi\u00f3n Europea afirm\u00f3 en 2018 que en realidad quiere que los pa\u00edses europeos elijan entre el horario de verano o el de invierno en lugar de cambiar el reloj.  El Parlamento Europeo tambi\u00e9n se pronunci\u00f3 a favor de ello.  Las encuestas tambi\u00e9n mostraron que muchos ciudadanos europeos estaban cansados \u200b\u200bde cambiar el reloj. <\/p>\n<p>Si los Pa\u00edses Bajos decidieran respetar siempre el horario de verano, afuera s\u00f3lo brillar\u00eda a las 9:45 de la ma\u00f1ana, el d\u00eda m\u00e1s corto del a\u00f1o.  Si eliges mantener el horario de invierno, oscurecer\u00e1 a las 9 p.m. en el d\u00eda de verano m\u00e1s largo del a\u00f1o. <\/p>\n<p>Todav\u00eda no est\u00e1 muy claro si los Pa\u00edses Bajos finalmente aceptar\u00e1n esto.  El gobierno dej\u00f3 claro en ese momento que pensaba que era importante ver primero a qu\u00e9 divisi\u00f3n horaria se adherir\u00edan los pa\u00edses vecinos.  De esta manera se mantendr\u00eda la conexi\u00f3n con nuestros vecinos m\u00e1s inmediatos. <\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.nhnieuws.nl\/nieuws\/326723\/klok-een-uurtje-terug-wat-zijn-de-voordelen-van-wintertijd\" rel=\"nofollow noopener\" target=\"_blank\">ttn-es-55<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los relojes se retrasar\u00e1n una hora esta noche. Eso significa una hora extra de sue\u00f1o, pero para muchas<\/p>\n","protected":false},"author":1,"featured_media":1019697,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[212535,4090,3910,38,3160,13216,5555,36,4969,1932,158],"class_list":["post-1019696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-atrasar","tag-beneficios","tag-cuales","tag-del","tag-hora","tag-horario","tag-invierno","tag-los","tag-reloj","tag-son","tag-una"],"_links":{"self":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1019696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/comments?post=1019696"}],"version-history":[{"count":0,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/posts\/1019696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media\/1019697"}],"wp:attachment":[{"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/media?parent=1019696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/categories?post=1019696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teknomers.com\/es\/wp-json\/wp\/v2\/tags?post=1019696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}